{"id":112,"date":"2021-12-19T22:23:00","date_gmt":"2021-12-19T21:23:00","guid":{"rendered":"https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/?p=112"},"modified":"2022-05-20T21:35:59","modified_gmt":"2022-05-20T19:35:59","slug":"adventsimpfen-mit-fast-300-impfungen-am-samstag","status":"publish","type":"post","link":"https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/2021\/12\/19\/adventsimpfen-mit-fast-300-impfungen-am-samstag\/","title":{"rendered":"Adventsimpfen mit fast 300 Impfungen am Samstag"},"content":{"rendered":"\n<p>Auch wenn es nicht zu unserer Kernaufgabe geh\u00f6rt hat das Team der Praxis Orthop\u00e4die Wilhelmstra\u00dfe mit allen \u00c4rzten am Samstag, 18.12.2021, Patienten und Impfwillige mit einer Boosterimpfung, aber auch einigen Erst- und Zweitimpfungen versorgt. Der professionelle Ablauf, keinerlei Wartezeiten und die gute Stimmung bei der Arbeit wurde von vielen Besuchern der Praxis sehr positiv aufgenommen. So konnten wir knapp 300 Wiesbadener und von ausw\u00e4rts Angereiste mit dem wichtigen &#8222;Pieks&#8220; versorgen. Toller Nebeneffekt ist auch eine aus den Erl\u00f6sen generierte Spende der Praxis f\u00fcr einen guten Zweck in Wiesbaden. Zu weiteren Impfterminen vor und nach Weihnachten k\u00f6nnen sich Interessierte auf dem COVID IMPF LINK [nbsp]oben auf der WEB site anmelden\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auch wenn es nicht zu unserer Kernaufgabe geh\u00f6rt hat das Team der Praxis Orthop\u00e4die Wilhelmstra\u00dfe mit allen \u00c4rzten am Samstag, 18.12.2021, Patienten und Impfwillige mit einer Boosterimpfung, aber auch einigen Erst- und Zweitimpfungen versorgt. Der professionelle Ablauf, keinerlei Wartezeiten und die gute Stimmung bei der Arbeit wurde von vielen Besuchern der Praxis sehr positiv aufgenommen. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":109,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"featured_image_urls_v2":{"full":["https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-content\/uploads\/2022\/04\/coronavirus-covid-19-attack-organism-corona-virus-2021-08-28-00-11-49-utc.jpg",2000,1000,false],"thumbnail":["https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-content\/uploads\/2022\/04\/coronavirus-covid-19-attack-organism-corona-virus-2021-08-28-00-11-49-utc-150x150.jpg",150,150,true],"medium":["https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-content\/uploads\/2022\/04\/coronavirus-covid-19-attack-organism-corona-virus-2021-08-28-00-11-49-utc-300x150.jpg",300,150,true],"medium_large":["https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-content\/uploads\/2022\/04\/coronavirus-covid-19-attack-organism-corona-virus-2021-08-28-00-11-49-utc-768x384.jpg",768,384,true],"large":["https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-content\/uploads\/2022\/04\/coronavirus-covid-19-attack-organism-corona-virus-2021-08-28-00-11-49-utc-1024x512.jpg",1024,512,true],"1536x1536":["https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-content\/uploads\/2022\/04\/coronavirus-covid-19-attack-organism-corona-virus-2021-08-28-00-11-49-utc-1536x768.jpg",1536,768,true],"2048x2048":["https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-content\/uploads\/2022\/04\/coronavirus-covid-19-attack-organism-corona-virus-2021-08-28-00-11-49-utc.jpg",2000,1000,false]},"post_excerpt_stackable_v2":"<p>Auch wenn es nicht zu unserer Kernaufgabe geh\u00f6rt hat das Team der Praxis Orthop\u00e4die Wilhelmstra\u00dfe mit allen \u00c4rzten am Samstag, 18.12.2021, Patienten und Impfwillige mit einer Boosterimpfung, aber auch einigen Erst- und Zweitimpfungen versorgt. Der professionelle Ablauf, keinerlei Wartezeiten und die gute Stimmung bei der Arbeit wurde von vielen Besuchern der Praxis sehr positiv aufgenommen. So konnten wir knapp 300 Wiesbadener und von ausw\u00e4rts Angereiste mit dem wichtigen &#8222;Pieks&#8220; versorgen. Toller Nebeneffekt ist auch eine aus den Erl\u00f6sen generierte Spende der Praxis f\u00fcr einen guten Zweck in Wiesbaden. Zu weiteren Impfterminen vor und nach Weihnachten k\u00f6nnen sich Interessierte auf dem&hellip;<\/p>\n","category_list_v2":"<a href=\"https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/category\/aktuelles\/\" rel=\"category tag\">Aktuelles<\/a>","author_info_v2":{"name":"Markus Giesa","url":"https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/author\/markus-giesa\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-json\/wp\/v2\/posts\/112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-json\/wp\/v2\/comments?post=112"}],"version-history":[{"count":2,"href":"https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-json\/wp\/v2\/posts\/112\/revisions"}],"predecessor-version":[{"id":273,"href":"https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-json\/wp\/v2\/posts\/112\/revisions\/273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-json\/wp\/v2\/media\/109"}],"wp:attachment":[{"href":"https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-json\/wp\/v2\/media?parent=112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-json\/wp\/v2\/categories?post=112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.orthopaedie-wilhelmstrasse.de\/news\/wp-json\/wp\/v2\/tags?post=112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}